{"id":10824,"date":"2024-01-11T08:20:13","date_gmt":"2024-01-11T07:20:13","guid":{"rendered":"https:\/\/www.graeber.rentals\/?post_type=stellenangebot&#038;p=10824"},"modified":"2025-08-20T14:55:03","modified_gmt":"2025-08-20T12:55:03","slug":"servicetechniker-in-fuer-donaueschingen-m-w-d","status":"publish","type":"stellenangebot","link":"https:\/\/www.graeber.rentals\/en\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/","title":{"rendered":"SERVICE TECHNICIAN FOR DONAUESCHINGEN (M\/F\/D)"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10824\" class=\"elementor elementor-10824\" data-elementor-post-type=\"stellenangebot\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c310c5c elementor-section-height-min-height elementor-section-items-stretch elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default\" data-id=\"c310c5c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe33900\" data-id=\"fe33900\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d921e71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d921e71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc4c408\" data-id=\"bc4c408\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3c5c7c elementor-widget__width-initial elementor-widget elementor-widget-jet-headline\" data-id=\"a3c5c7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"jet-headline jet-headline--direction-vertical\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">SERVICE TECHNICIAN FOR DONAUESCHINGEN (M\/F\/D)<\/span><\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">Branch office in Donaueschingen<\/span><\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f06f2d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f06f2d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-74b21d7\" data-id=\"74b21d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15cd3cb elementor-widget elementor-widget-heading\" data-id=\"15cd3cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">YOUR TASKS WITH US:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86940ea elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"86940ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>\n<p>You look after our equipment fleet and use your expertise to ensure that our machines run smoothly<\/p>\n<\/li>\n<li>\n<p>The operational safety of our machines is close to your heart<\/p>\n<\/li>\n<li>You stand for our products and become a professional in the mechanical field of height access technology<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79299db elementor-widget elementor-widget-spacer\" data-id=\"79299db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8abcd14 elementor-widget elementor-widget-heading\" data-id=\"8abcd14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">THIS IS WHAT YOU BRING WITH YOU:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-469df70 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"469df70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Completed technical training (e.g. agricultural or construction machinery mechanic, automotive mechatronics technician or master craftsman)<\/li><li>You are communicative, a flexible team player and enjoy machines and technology<\/li><li>Distinct customer orientation, polite and well-groomed appearance<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c3df77 elementor-widget elementor-widget-spacer\" data-id=\"7c3df77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d20e33 elementor-widget elementor-widget-heading\" data-id=\"3d20e33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">THAT AWAITS YOU WITH US:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d3a986 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9d3a986\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Challenging and varied activities with a future<\/li><li>Opportunities for further education<\/li><li><p>High quality and modern workwear for every season<\/p><\/li><li><p>Long-term cooperation due to unlimited employment contract<\/p><\/li><li><p>Performance-related and attractive remuneration<\/p><\/li><li><p>Flat hierarchies in a young and young at heart team<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51820c3 elementor-widget elementor-widget-spacer\" data-id=\"51820c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2d3b14 elementor-widget elementor-widget-text-editor\" data-id=\"b2d3b14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We rely on the strengths of the individual and achieve outstanding results as a team - at the same time we enjoy our work, which brings many challenges. Every day! We offer you independent work with creative freedom in a future-proof workplace in a growing industry.<\/p><p>You enjoy working with people, are committed, reliable and like to work in a team? Then we look forward to receiving your application!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bfb08f elementor-widget elementor-widget-text-editor\" data-id=\"9bfb08f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contact person: Patrick Fromm<br \/>Phone: <a href=\"tel:+49771 89868912\">+49 (0) 771 898689-12<\/a><br \/>Email: <a href=\"mailto:fromm@graeber.gmbh\">fromm@graeber.gmbh<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-270e57d elementor-widget elementor-widget-button\" data-id=\"270e57d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:fromm@graeber.gmbh\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Apply now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-792d4d4\" data-id=\"792d4d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bc6c153 align-left elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc6c153\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-86d45c6\" data-id=\"86d45c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f6f057 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"5f6f057\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.graeber.rentals\/wp-content\/uploads\/2025\/08\/Servicetechnikerin_Donaueschingen_20082025.pdf\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2825fe elementor-widget elementor-widget-spacer\" data-id=\"e2825fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c74332 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6c74332\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.graeber.rentals\/wp-content\/uploads\/2025\/08\/Servicetechnikerin_Donaueschingen_20082025.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download job offer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8a1edb elementor-widget elementor-widget-spacer\" data-id=\"d8a1edb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fbb54b6 align-left elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbb54b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ee97e73\" data-id=\"ee97e73\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09ba65f elementor-widget elementor-widget-heading\" data-id=\"09ba65f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">BRIEF OVERVIEW<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf64eea elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bf64eea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">SERVICE TECHNICIAN FOR DONAUESCHINGEN (M\/F\/D)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Donaueschingen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Unlimited<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Full-time<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25f8f18 elementor-widget elementor-widget-text-editor\" data-id=\"25f8f18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Earnings: According to agreement<br \/>Start of work: immediately<br \/>Willingness to travel: not required<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a71585 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0a71585\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:fromm@graeber.gmbh\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Apply now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dc4ffc elementor-widget elementor-widget-spacer\" data-id=\"3dc4ffc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58e5755 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58e5755\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9fe4caf\" data-id=\"9fe4caf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"einstiegslevel":[45,46],"einsatzbereiche":[],"standorte":[13],"class_list":["post-10824","stellenangebot","type-stellenangebot","status-publish","hentry","einstiegslevel-anfaenger","einstiegslevel-erfahren","standorte-donaueschingen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SERVICETECHNIKER\/IN F\u00dcR DONAUESCHINGEN (M\/W\/D) - Gr\u00e4ber - Rentals<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.graeber.rentals\/en\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERVICETECHNIKER\/IN F\u00dcR DONAUESCHINGEN (M\/W\/D) - Gr\u00e4ber - Rentals\" \/>\n<meta property=\"og:description\" content=\"DEINE AUFGABEN BEI UNS: Du betreust unseren Ger\u00e4tepark und sorgst mit deinem Knowhow f\u00fcr reibungslose Funktion unserer Maschinen Die Betriebssicherheit unserer Maschinen liegt dir am Herzen Du stehst f\u00fcr unsere Produkte und wirst zum Profi im maschinellen Bereich der H\u00f6henzugangstechnik DAS BRINGST DU MIT: Abgeschlossene technische Ausbildung (z.b. Land- oder Baumaschinenmechaniker\/in, KFZ-Mechatroniker\/in o.Meister\/in) Du bist [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.graeber.rentals\/en\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/\" \/>\n<meta property=\"og:site_name\" content=\"Gr\u00e4ber - Rentals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/graeber.ag\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-20T12:55:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.graeber.rentals\/wp-content\/uploads\/2025\/08\/Servicetechnikerin_Donaueschingen_20082025.pdf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/stellenangebot\\\/servicetechniker-in-fuer-donaueschingen-m-w-d\\\/\",\"url\":\"https:\\\/\\\/www.graeber.rentals\\\/stellenangebot\\\/servicetechniker-in-fuer-donaueschingen-m-w-d\\\/\",\"name\":\"SERVICETECHNIKER\\\/IN F\u00dcR DONAUESCHINGEN (M\\\/W\\\/D) - Gr\u00e4ber - Rentals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/stellenangebot\\\/servicetechniker-in-fuer-donaueschingen-m-w-d\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/stellenangebot\\\/servicetechniker-in-fuer-donaueschingen-m-w-d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.graeber.rentals\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Servicetechnikerin_Donaueschingen_20082025.pdf\",\"datePublished\":\"2024-01-11T07:20:13+00:00\",\"dateModified\":\"2025-08-20T12:55:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/stellenangebot\\\/servicetechniker-in-fuer-donaueschingen-m-w-d\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.graeber.rentals\\\/stellenangebot\\\/servicetechniker-in-fuer-donaueschingen-m-w-d\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/stellenangebot\\\/servicetechniker-in-fuer-donaueschingen-m-w-d\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.graeber.rentals\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Servicetechnikerin_Donaueschingen_20082025.pdf\",\"contentUrl\":\"https:\\\/\\\/www.graeber.rentals\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Servicetechnikerin_Donaueschingen_20082025.pdf\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/stellenangebot\\\/servicetechniker-in-fuer-donaueschingen-m-w-d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.graeber.rentals\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERVICETECHNIKER\\\/IN F\u00dcR DONAUESCHINGEN (M\\\/W\\\/D)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/#website\",\"url\":\"https:\\\/\\\/www.graeber.rentals\\\/\",\"name\":\"Gr\u00e4ber - Rentals\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.graeber.rentals\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/#organization\",\"name\":\"Gr\u00e4ber - Rentals\",\"url\":\"https:\\\/\\\/www.graeber.rentals\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.graeber.rentals\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/220928_GH_Logo_ohne_Claim_ohne_Kugel.png\",\"contentUrl\":\"https:\\\/\\\/www.graeber.rentals\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/220928_GH_Logo_ohne_Claim_ohne_Kugel.png\",\"width\":1610,\"height\":206,\"caption\":\"Gr\u00e4ber - Rentals\"},\"image\":{\"@id\":\"https:\\\/\\\/www.graeber.rentals\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/graeber.ag\\\/\",\"https:\\\/\\\/www.instagram.com\\\/p\\\/CM390AuKLO8\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERVICE TECHNICIAN FOR DONAUESCHINGEN (M\/F\/D) - Gr\u00e4ber - Rentals","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.graeber.rentals\/en\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/","og_locale":"en_US","og_type":"article","og_title":"SERVICETECHNIKER\/IN F\u00dcR DONAUESCHINGEN (M\/W\/D) - Gr\u00e4ber - Rentals","og_description":"DEINE AUFGABEN BEI UNS: Du betreust unseren Ger\u00e4tepark und sorgst mit deinem Knowhow f\u00fcr reibungslose Funktion unserer Maschinen Die Betriebssicherheit unserer Maschinen liegt dir am Herzen Du stehst f\u00fcr unsere Produkte und wirst zum Profi im maschinellen Bereich der H\u00f6henzugangstechnik DAS BRINGST DU MIT: Abgeschlossene technische Ausbildung (z.b. Land- oder Baumaschinenmechaniker\/in, KFZ-Mechatroniker\/in o.Meister\/in) Du bist [&hellip;]","og_url":"https:\/\/www.graeber.rentals\/en\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/","og_site_name":"Gr\u00e4ber - Rentals","article_publisher":"https:\/\/www.facebook.com\/graeber.ag\/","article_modified_time":"2025-08-20T12:55:03+00:00","og_image":[{"url":"https:\/\/www.graeber.rentals\/wp-content\/uploads\/2025\/08\/Servicetechnikerin_Donaueschingen_20082025.pdf","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.graeber.rentals\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/","url":"https:\/\/www.graeber.rentals\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/","name":"SERVICE TECHNICIAN FOR DONAUESCHINGEN (M\/F\/D) - Gr\u00e4ber - Rentals","isPartOf":{"@id":"https:\/\/www.graeber.rentals\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.graeber.rentals\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/#primaryimage"},"image":{"@id":"https:\/\/www.graeber.rentals\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/#primaryimage"},"thumbnailUrl":"https:\/\/www.graeber.rentals\/wp-content\/uploads\/2025\/08\/Servicetechnikerin_Donaueschingen_20082025.pdf","datePublished":"2024-01-11T07:20:13+00:00","dateModified":"2025-08-20T12:55:03+00:00","breadcrumb":{"@id":"https:\/\/www.graeber.rentals\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.graeber.rentals\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.graeber.rentals\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/#primaryimage","url":"https:\/\/www.graeber.rentals\/wp-content\/uploads\/2025\/08\/Servicetechnikerin_Donaueschingen_20082025.pdf","contentUrl":"https:\/\/www.graeber.rentals\/wp-content\/uploads\/2025\/08\/Servicetechnikerin_Donaueschingen_20082025.pdf"},{"@type":"BreadcrumbList","@id":"https:\/\/www.graeber.rentals\/stellenangebot\/servicetechniker-in-fuer-donaueschingen-m-w-d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.graeber.rentals\/"},{"@type":"ListItem","position":2,"name":"SERVICETECHNIKER\/IN F\u00dcR DONAUESCHINGEN (M\/W\/D)"}]},{"@type":"WebSite","@id":"https:\/\/www.graeber.rentals\/#website","url":"https:\/\/www.graeber.rentals\/","name":"Gr\u00e4ber - Rentals","description":"","publisher":{"@id":"https:\/\/www.graeber.rentals\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.graeber.rentals\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.graeber.rentals\/#organization","name":"Gr\u00e4ber - Rentals","url":"https:\/\/www.graeber.rentals\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.graeber.rentals\/#\/schema\/logo\/image\/","url":"https:\/\/www.graeber.rentals\/wp-content\/uploads\/2022\/09\/220928_GH_Logo_ohne_Claim_ohne_Kugel.png","contentUrl":"https:\/\/www.graeber.rentals\/wp-content\/uploads\/2022\/09\/220928_GH_Logo_ohne_Claim_ohne_Kugel.png","width":1610,"height":206,"caption":"Gr\u00e4ber - Rentals"},"image":{"@id":"https:\/\/www.graeber.rentals\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/graeber.ag\/","https:\/\/www.instagram.com\/p\/CM390AuKLO8\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.graeber.rentals\/en\/wp-json\/wp\/v2\/stellenangebot\/10824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.graeber.rentals\/en\/wp-json\/wp\/v2\/stellenangebot"}],"about":[{"href":"https:\/\/www.graeber.rentals\/en\/wp-json\/wp\/v2\/types\/stellenangebot"}],"version-history":[{"count":18,"href":"https:\/\/www.graeber.rentals\/en\/wp-json\/wp\/v2\/stellenangebot\/10824\/revisions"}],"predecessor-version":[{"id":12388,"href":"https:\/\/www.graeber.rentals\/en\/wp-json\/wp\/v2\/stellenangebot\/10824\/revisions\/12388"}],"wp:attachment":[{"href":"https:\/\/www.graeber.rentals\/en\/wp-json\/wp\/v2\/media?parent=10824"}],"wp:term":[{"taxonomy":"einstiegslevel","embeddable":true,"href":"https:\/\/www.graeber.rentals\/en\/wp-json\/wp\/v2\/einstiegslevel?post=10824"},{"taxonomy":"einsatzbereiche","embeddable":true,"href":"https:\/\/www.graeber.rentals\/en\/wp-json\/wp\/v2\/einsatzbereiche?post=10824"},{"taxonomy":"standorte","embeddable":true,"href":"https:\/\/www.graeber.rentals\/en\/wp-json\/wp\/v2\/standorte?post=10824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}